{"id":179,"date":"2020-11-12T13:32:11","date_gmt":"2020-11-12T06:32:11","guid":{"rendered":"http:\/\/localhost\/dcdc20\/?p=179"},"modified":"2020-11-16T15:23:13","modified_gmt":"2020-11-16T08:23:13","slug":"dangfever","status":"publish","type":"post","link":"https:\/\/cdc.gov.la\/index.php\/2020\/11\/12\/dangfever\/","title":{"rendered":"\u0ec0\u0eaa\u0e8d\u0e8a\u0eb4\u0ea7\u0eb4\u0e94\u0ec3\u0edd\u0ec8\u0ec0\u0e9e\u0eb5\u0ec8\u0ea1\u0e82\u0eb7\u0ec9\u0e99 1 \u0e84\u0ebb\u0e99 \u0e8d\u0ec9\u0ead\u0e99\u0ec4\u0e82\u0ec9\u0e8d\u0eb8\u0e87\u0ea5\u0eb2\u0e8d"},"content":{"rendered":"<p>\u0e81\u0ebb\u0ea1\u0e84\u0ea7\u0e9a\u0e84\u0eb8\u0ea1\u0e9e\u0eb0\u0e8d\u0eb2\u0e94\u0e95\u0eb4\u0e94\u0e95\u0ecd\u0ec8 \u0e81\u0eb0\u0e8a\u0ea7\u0e87\u0eaa\u0eb2\u0e97\u0eb2\u0ea5\u0eb0\u0e99\u0eb0\u0eaa\u0eb8\u0e81 \u0ec4\u0e94\u0ec9\u0ea5\u0eb2\u0e8d\u0e87\u0eb2\u0e99\u0ec3\u0eab\u0ec9\u0eae\u0eb9\u0ec9\u0ea7\u0eb1\u0e99\u0e97\u0eb5 21 \u0e81\u0eb1\u0e99\u0e8d\u0eb2 2020 \u0ea7\u0ec8\u0eb2: \u0ea1\u0eb5\u0e9c\u0eb9\u0ec9\u0ec0\u0eaa\u0e8d\u0e8a\u0eb4\u0ea7\u0eb4\u0e94\u0e8d\u0ec9\u0ead\u0e99\u0e9e\u0eb0\u0e8d\u0eb2\u0e94\u0ec4\u0e82\u0ec9\u0e8d\u0eb8\u0e87\u0ea5\u0eb2\u0e8d\u0eaa\u0eb0\u0eaa\u0ebb\u0ea1 12 \u0e84\u0ebb\u0e99\u0ec3\u0e99\u0e97\u0ebb\u0ec8\u0ea7\u0e9b\u0eb0\u0ec0\u0e97\u0e94. \u0ec3\u0e99\u0e99\u0eb1\u0ec9\u0e99, \u0ec0\u0eaa\u0e8d\u0e8a\u0eb4\u0ea7\u0eb4\u0e94\u0ec3\u0edd\u0ec8\u0ec0\u0e9e\u0eb5\u0ec8\u0ea1\u0e82\u0eb7\u0ec9\u0e99 1 \u0e84\u0ebb\u0e99 \u0ea2\u0eb9\u0ec8\u0e9a\u0ec9\u0eb2\u0e99\u0e8d\u0ecd\u0ec9, \u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0e9a\u0eb9\u0e99\u0ec0\u0edc\u0eb7\u0ead \u0ec1\u0e82\u0ea7\u0e87 \u0e9c\u0ebb\u0ec9\u0e87\u0eaa\u0eb2\u0ea5\u0eb5, \u0ea5\u0ea7\u0ea1\u0ec0\u0e9b\u0eb1\u0e99 6 \u0ec1\u0e82\u0ea7\u0e87 \u0ec1\u0ea5\u0eb0 \u0e99\u0eb0\u0e84\u0ead\u0e99\u0eab\u0ebc\u0ea7\u0e87\u0ea7\u0ebd\u0e87\u0e88\u0eb1\u0e99 \u0e97\u0eb5\u0ec8\u0e9e\u0ebb\u0e9a\u0e81\u0ecd \u0ea5\u0eb0\u0e99\u0eb5\u0e9c\u0eb9\u0ec9\u0ec0\u0eaa\u0e8d\u0e8a\u0eb4\u0ea7\u0eb4\u0e94.<\/p>\n<p>\u0ea1\u0eb2\u0eae\u0ead\u0e94\u0e9b\u0eb1\u0e94\u0e88\u0eb8\u0e9a\u0eb1\u0e99 \u0e9e\u0ebb\u0e9a\u0e9c\u0eb9\u0ec9\u0e95\u0eb4\u0e94\u0ec0\u0e8a\u0eb7\u0ec9\u0ead\u0ec1\u0ea5\u0ec9\u0ea7 6.531 \u0e81\u0ecd\u0ea5\u0eb0\u0e99\u0eb5 \u0ec3\u0e99\u0e97\u0ebb\u0ec8\u0ea7\u0e9b\u0eb0\u0ec0\u0e97\u0e94, \u0eab\u0ebc\u0eb2\u0e8d\u0e81\u0ea7\u0ec8\u0eb2\u0edd\u0eb9\u0ec8 \u0ec1\u0ea1\u0ec8\u0e99\u0ea2\u0eb9\u0ec8\u0e99\u0eb0\u0e84\u0ead\u0e99 \u0eab\u0ebc\u0ea7\u0e87\u0ea7\u0ebd\u0e87\u0e88\u0eb1\u0e99 1. 529 \u0e81\u0ecd\u0ea5\u0eb0\u0e99\u0eb5 , \u0e96\u0eb1\u0e94\u0ea5\u0ebb\u0e87\u0ea1\u0eb2\u0ec1\u0ea1\u0ec8\u0e99 \u0ec1\u0e82\u0ea7\u0e87\u0e9a\u0ecd\u0ea5\u0eb4\u0e84\u0eb3\u0ec4\u0e8a 741 \u0e84\u0ebb\u0e99, \u0ea7\u0ebd\u0e87\u0e88\u0eb1\u0e99 650 \u0e84\u0ebb\u0e99, \u0e9a\u0ecd\u0ec8\u0ec1\u0e81\u0ec9\u0ea7 654 \u0e84\u0ebb\u0e99, \u0eaa\u0eb0\u0eab\u0ea7\u0eb1\u0e99\u0e99\u0eb0\u0ec0\u0e82\u0e94 641 \u0e84\u0ebb\u0e99 \u0ec1\u0ea5\u0eb0 \u0ec1\u0e82\u0ea7\u0e87 \u0ead\u0eb7\u0ec8\u0e99\u0ec6. \u0ec3\u0e99\u0e99\u0eb1\u0ec9\u0e99, \u0ec0\u0eaa\u0e8d\u0e8a\u0eb5\u0ea7\u0eb4\u0e94\u0ea5\u0ea7\u0ea1\u0ec1\u0ea5\u0ec9\u0ea7 12 \u0e84\u0ebb\u0e99 (\u0e99\u0eb0 \u0e84\u0ead\u0e99\u0eab\u0ebc\u0ea7\u0e87\u0ea7\u0ebd\u0e87\u0e88\u0eb1\u0e99 04 \u0e84\u0ebb\u0e99, \u0ec1\u0e82\u0ea7\u0e87 \u0e9a\u0ecd\u0ea5\u0eb4\u0e84\u0ecd\u0eb2\u0ec4\u0e8a 02 \u0e84\u0ebb\u0e99, \u0e84\u0eb3\u0ea1\u0ec8\u0ea7\u0e99 02\u0e84\u0ebb\u0e99, \u0ec4\u0e8a\u0e8d\u0eb0\u0e9a\u0eb9\u0ea5\u0eb5 01 \u0e84\u0ebb\u0e99, \u0e8a\u0ebd\u0e87\u0e82\u0ea7\u0eb2\u0e87 01 \u0e84\u0ebb\u0e99, \u0eaa\u0eb0\u0eab\u0ea7\u0eb1\u0e99\u0e99\u0eb0\u0ec0\u0e82\u0e94 01 \u0e84\u0ebb\u0e99 \u0ec1\u0ea5\u0eb0 \u0e9c\u0ebb\u0ec9\u0e87\u0eaa\u0eb2\u0ea5\u0eb5 01 \u0e84\u0ebb\u0e99).<\/p>\n<p>\u0e95\u0ecd\u0ec8\u0eaa\u0eb0\u0e9e\u0eb2\u0e9a\u0e81\u0eb2\u0e99\u0ec1\u0e9c\u0ec8\u0ea5\u0eb0\u0e9a\u0eb2\u0e94\u0e9e\u0eb0\u0e8d\u0eb2\u0e94\u0ec4\u0e82\u0ec9\u0e8d\u0eb8\u0e87\u0ea5\u0eb2\u0e8d\u0e94\u0eb1\u0ec8\u0e87\u0e81\u0ec8\u0eb2\u0ea7, \u0eaa\u0eb0\u0e99\u0eb1\u0ec9\u0e99, \u0e88\u0eb6\u0ec8\u0e87\u0e82\u0ecd\u0eae\u0ebd\u0e81\u0eae\u0ec9\u0ead\u0e87\u0ea1\u0eb2\u0e8d\u0eb1\u0e87 \u0e9e\u0ecd\u0ec8\u0ec1\u0ea1\u0ec8\u0e9b\u0eb0\u0e8a\u0eb2\u0e8a\u0ebb\u0e99, \u0e8a\u0eb8\u0ea1\u0e8a\u0ebb\u0e99 \u0ec1\u0ea5\u0eb0 \u0ead\u0eb3\u0e99\u0eb2\u0e94\u0e81\u0eb2\u0e99\u0e9b\u0ebb\u0e81\u0e84\u0ead\u0e87\u0e97\u0eb8\u0e81\u0e82\u0eb1\u0ec9\u0ec9\u0e99 \u0eae\u0ec8\u0ea7\u0ea1\u0ec1\u0eae\u0e87\u0eae\u0ec8\u0ea7\u0ea1\u0ec3\u0e88 \u0ec3\u0e99\u0e81\u0eb2\u0e99\u0e9b\u0eb0\u0e95\u0eb4\u0e9a\u0eb1\u0e94 5 \u0e9b \u0ea2\u0ec8\u0eb2\u0e87\u0ec0\u0e84\u0eb1\u0ec8\u0e87\u0e84\u0eb1\u0e94 \u0ec3\u0eab\u0ec9\u0ec0\u0e9b\u0eb1\u0e99\u0e9b\u0eb0\u0e88\u0eb3 \u0e88\u0eb6\u0ec8\u0e87\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e97\u0eb3\u0ea5\u0eb2\u0e8d\u0ec1\u0eab\u0ebc\u0ec8\u0e87\u0ec0\u0e9e\u0eb2\u0eb0\u0e9e\u0eb1\u0e99\u0e82\u0ead\u0e87\u0e8d\u0eb8\u0e87\u0ec4\u0e94\u0ec9 \u0ec3\u0eab\u0ec9\u0e96\u0eb7\u0ea7\u0ec8\u0eb2\u0ec1\u0ea1\u0ec8\u0e99\u0edc\u0ec9\u0eb2\u0e97\u0eb5\u0ec8, \u0e84\u0ea7\u0eb2\u0ea1\u0eae\u0eb1\u0e9a\u0e9c\u0eb4\u0e94\u0e8a\u0ead\u0e9a\u0e82\u0ead\u0e87\u0edd\u0ebb\u0e94\u0e97\u0eb8\u0e81\u0e84\u0ebb\u0e99.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e81\u0ebb\u0ea1\u0e84\u0ea7\u0e9a\u0e84\u0eb8\u0ea1\u0e9e\u0eb0\u0e8d\u0eb2\u0e94\u0e95\u0eb4\u0e94\u0e95\u0ecd\u0ec8 \u0e81\u0eb0\u0e8a\u0ea7\u0e87\u0eaa\u0eb2\u0e97\u0eb2\u0ea5\u0eb0\u0e99\u0eb0\u0eaa\u0eb8\u0e81 \u0ec4\u0e94\u0ec9\u0ea5\u0eb2\u0e8d\u0e87\u0eb2\u0e99\u0ec3\u0eab\u0ec9\u0eae\u0eb9\u0ec9\u0ea7\u0eb1\u0e99\u0e97\u0eb5 21 \u0e81\u0eb1\u0e99\u0e8d\u0eb2 2020 \u0ea7\u0ec8\u0eb2: \u0ea1\u0eb5\u0e9c\u0eb9\u0ec9\u0ec0\u0eaa\u0e8d\u0e8a\u0eb4\u0ea7\u0eb4\u0e94\u0e8d\u0ec9\u0ead\u0e99\u0e9e\u0eb0\u0e8d\u0eb2\u0e94\u0ec4\u0e82\u0ec9\u0e8d\u0eb8\u0e87\u0ea5\u0eb2\u0e8d\u0eaa\u0eb0\u0eaa\u0ebb\u0ea1 12 \u0e84\u0ebb\u0e99\u0ec3\u0e99\u0e97\u0ebb\u0ec8\u0ea7\u0e9b\u0eb0\u0ec0\u0e97\u0e94. \u0ec3\u0e99\u0e99\u0eb1\u0ec9\u0e99, \u0ec0\u0eaa\u0e8d\u0e8a\u0eb4\u0ea7\u0eb4\u0e94\u0ec3\u0edd\u0ec8\u0ec0\u0e9e\u0eb5\u0ec8\u0ea1\u0e82\u0eb7\u0ec9\u0e99 1 \u0e84\u0ebb\u0e99 \u0ea2\u0eb9\u0ec8\u0e9a\u0ec9\u0eb2\u0e99\u0e8d\u0ecd\u0ec9,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":181,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,31],"tags":[],"class_list":["post-179","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-18","category-31"],"featured_image_urls":{"full":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/9.jpg",696,364,false],"thumbnail":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/9-150x150.jpg",150,150,true],"medium":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/9-300x157.jpg",300,157,true],"medium_large":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/9.jpg",640,335,false],"large":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/9.jpg",640,335,false],"1536x1536":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/9.jpg",696,364,false],"2048x2048":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/9.jpg",696,364,false],"covernews-featured":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/9.jpg",696,364,false],"covernews-medium":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/9.jpg",540,282,false]},"author_info":{"display_name":"admin","author_link":"https:\/\/cdc.gov.la\/index.php\/author\/admin\/"},"category_info":"<a href=\"https:\/\/cdc.gov.la\/index.php\/category\/%e0%ba%82%e0%bb%88%e0%ba%b2%e0%ba%a7\/\" rel=\"category tag\">\u0e82\u0ec8\u0eb2\u0ea7<\/a> <a href=\"https:\/\/cdc.gov.la\/index.php\/category\/%e0%ba%82%e0%bb%88%e0%ba%b2%e0%ba%a7%e0%ba%94%e0%bb%88%e0%ba%a7%e0%ba%99\/\" rel=\"category tag\">\u0e82\u0ec8\u0eb2\u0ea7\u0e94\u0ec8\u0ea7\u0e99<\/a>","tag_info":"\u0e82\u0ec8\u0eb2\u0ea7\u0e94\u0ec8\u0ea7\u0e99","comment_count":"0","rttpg_featured_image_url":{"full":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/9.jpg",696,364,false],"landscape":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/9.jpg",696,364,false],"portraits":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/9.jpg",696,364,false],"thumbnail":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/9-150x150.jpg",150,150,true],"medium":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/9-300x157.jpg",300,157,true],"large":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/9.jpg",640,335,false],"1536x1536":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/9.jpg",696,364,false],"2048x2048":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/9.jpg",696,364,false],"covernews-featured":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/9.jpg",696,364,false],"covernews-medium":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/9.jpg",540,282,false]},"rttpg_author":{"display_name":"admin","author_link":"https:\/\/cdc.gov.la\/index.php\/author\/admin\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/cdc.gov.la\/index.php\/category\/%e0%ba%82%e0%bb%88%e0%ba%b2%e0%ba%a7\/\" rel=\"category tag\">\u0e82\u0ec8\u0eb2\u0ea7<\/a> <a href=\"https:\/\/cdc.gov.la\/index.php\/category\/%e0%ba%82%e0%bb%88%e0%ba%b2%e0%ba%a7%e0%ba%94%e0%bb%88%e0%ba%a7%e0%ba%99\/\" rel=\"category tag\">\u0e82\u0ec8\u0eb2\u0ea7\u0e94\u0ec8\u0ea7\u0e99<\/a>","rttpg_excerpt":"\u0e81\u0ebb\u0ea1\u0e84\u0ea7\u0e9a\u0e84\u0eb8\u0ea1\u0e9e\u0eb0\u0e8d\u0eb2\u0e94\u0e95\u0eb4\u0e94\u0e95\u0ecd\u0ec8 \u0e81\u0eb0\u0e8a\u0ea7\u0e87\u0eaa\u0eb2\u0e97\u0eb2\u0ea5\u0eb0\u0e99\u0eb0\u0eaa\u0eb8\u0e81 \u0ec4\u0e94\u0ec9\u0ea5\u0eb2\u0e8d\u0e87\u0eb2\u0e99\u0ec3\u0eab\u0ec9\u0eae\u0eb9\u0ec9\u0ea7\u0eb1\u0e99\u0e97\u0eb5 21 \u0e81\u0eb1\u0e99\u0e8d\u0eb2 2020 \u0ea7\u0ec8\u0eb2: \u0ea1\u0eb5\u0e9c\u0eb9\u0ec9\u0ec0\u0eaa\u0e8d\u0e8a\u0eb4\u0ea7\u0eb4\u0e94\u0e8d\u0ec9\u0ead\u0e99\u0e9e\u0eb0\u0e8d\u0eb2\u0e94\u0ec4\u0e82\u0ec9\u0e8d\u0eb8\u0e87\u0ea5\u0eb2\u0e8d\u0eaa\u0eb0\u0eaa\u0ebb\u0ea1 12 \u0e84\u0ebb\u0e99\u0ec3\u0e99\u0e97\u0ebb\u0ec8\u0ea7\u0e9b\u0eb0\u0ec0\u0e97\u0e94. \u0ec3\u0e99\u0e99\u0eb1\u0ec9\u0e99, \u0ec0\u0eaa\u0e8d\u0e8a\u0eb4\u0ea7\u0eb4\u0e94\u0ec3\u0edd\u0ec8\u0ec0\u0e9e\u0eb5\u0ec8\u0ea1\u0e82\u0eb7\u0ec9\u0e99 1 \u0e84\u0ebb\u0e99 \u0ea2\u0eb9\u0ec8\u0e9a\u0ec9\u0eb2\u0e99\u0e8d\u0ecd\u0ec9,...","_links":{"self":[{"href":"https:\/\/cdc.gov.la\/index.php\/wp-json\/wp\/v2\/posts\/179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdc.gov.la\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdc.gov.la\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdc.gov.la\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cdc.gov.la\/index.php\/wp-json\/wp\/v2\/comments?post=179"}],"version-history":[{"count":1,"href":"https:\/\/cdc.gov.la\/index.php\/wp-json\/wp\/v2\/posts\/179\/revisions"}],"predecessor-version":[{"id":182,"href":"https:\/\/cdc.gov.la\/index.php\/wp-json\/wp\/v2\/posts\/179\/revisions\/182"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdc.gov.la\/index.php\/wp-json\/wp\/v2\/media\/181"}],"wp:attachment":[{"href":"https:\/\/cdc.gov.la\/index.php\/wp-json\/wp\/v2\/media?parent=179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdc.gov.la\/index.php\/wp-json\/wp\/v2\/categories?post=179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdc.gov.la\/index.php\/wp-json\/wp\/v2\/tags?post=179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}