{"id":192,"date":"2020-11-12T13:41:26","date_gmt":"2020-11-12T06:41:26","guid":{"rendered":"http:\/\/localhost\/dcdc20\/?p=192"},"modified":"2020-11-16T15:22:27","modified_gmt":"2020-11-16T08:22:27","slug":"newwavecovid19","status":"publish","type":"post","link":"https:\/\/cdc.gov.la\/index.php\/2020\/11\/12\/newwavecovid19\/","title":{"rendered":"\u0ea5\u0eb2\u0ea7\u0e8d\u0eb1\u0e87\u0ea1\u0eb5\u0e84\u0ea7\u0eb2\u0ea1\u0eaa\u0ec8\u0ebd\u0e87\u0e97\u0eb5\u0ec8\u0ead\u0eb2\u0e94\u0ec0\u0e81\u0eb5\u0e94\u0e81\u0eb2\u0e99\u0ea5\u0eb0\u0e9a\u0eb2\u0e94\u0e82\u0ead\u0e87\u0e9e\u0eb0\u0e8d\u0eb2\u0e94\u0ec2\u0e84\u0ea7\u0eb4\u0e94-19 \u0e82\u0eb6\u0ec9\u0e99\u0eae\u0ead\u0e9a\u0ec3\u0edd\u0ec8"},"content":{"rendered":"<p>\u0eab\u0ec9\u0ead\u0e87\u0ea7\u0ec8\u0eb2\u0e81\u0eb2\u0e99\u0eaa\u0ecd\u0eb2\u0e99\u0eb1\u0e81\u0e87\u0eb2\u0e99\u0e99\u0eb2\u0e8d\u0ebb\u0e81\u0ea5\u0eb1\u0e94\u0e96\u0eb0\u0ea1\u0ebb\u0e99\u0e95\u0eb5 \u0ec4\u0e94\u0ec9\u0ead\u0ead\u0e81\u0ec1\u0e88\u0ec9\u0e87\u0e81\u0eb2\u0e99\u0e94\u0ec8\u0ea7\u0e99\u0ec3\u0e99\u0ea1\u0eb7\u0ec9\u0ea7\u0eb1\u0e99\u0e97\u0eb5 7 \u0eaa\u0eb4\u0e87\u0eab\u0eb2 \u0e97\u0eb5\u0ec8\u0e9c\u0ec8\u0eb2\u0e99\u0ea1\u0eb2 \u0ec0\u0e96\u0eb5\u0e87\u0e97\u0eb8\u0e81\u0e9e\u0eb2\u0e81\u0eaa\u0ec8\u0ea7\u0e99\u0ea5\u0ea7\u0ea1\u0e97\u0eb1\u0e87\u0e9e\u0ecd\u0ec8\u0ec1\u0ea1\u0ec8\u0e9b\u0eb0\u0e8a\u0eb2\u0e8a\u0ebb\u0e99\u0e9a\u0eb1\u0e99\u0e94\u0eb2\u0ec0\u0e9c\u0ebb\u0ec8\u0eb2\u0ec3\u0e99\u0e82\u0ead\u0e9a\u0ec0\u0e82\u0e94\u0e97\u0ebb\u0ec8\u0ea7\u0e9b\u0eb0\u0ec0\u0e97\u0e94\u0ec3\u0eab\u0ec9\u0ec0\u0e9e\u0eb5\u0ec8\u0ea1\u0e97\u0eb0\u0ea7\u0eb5\u0e82\u0eb6\u0ec9\u0e99\u0e81\u0ea7\u0ec8\u0eb2\u0ec0\u0e81\u0ebb\u0ec8\u0eb2\u0e81\u0ec8\u0ebd\u0ea7\u0e81\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0e9b\u0eb0\u0e95\u0eb4\u0e9a\u0eb1\u0e94\u0ea1\u0eb2\u0e94\u0e95\u0eb0\u0e81\u0eb2\u0e99\u0e9c\u0ec8\u0ead\u0e99\u0e9c\u0eb1\u0e99\u0e9b\u0ec9\u0ead\u0e87 \u0e81\u0eb1\u0e99, \u0e84\u0ea7\u0e9a\u0e84\u0eb8\u0ea1, \u0eaa\u0eb0\u0e81\u0eb1\u0e94\u0e81\u0eb1\u0ec9\u0e99 \u0ec1\u0ea5\u0eb0 \u0ec1\u0e81\u0ec9\u0ec4\u0e82\u0e81\u0eb2\u0e99\u0ec1\u0e9c\u0ec8\u0ea5\u0eb0\u0e9a\u0eb2\u0e94\u0e82\u0ead\u0e87\u0e9e\u0eb0\u0e8d\u0eb2\u0e94\u0ec2\u0e84\u0ea7\u0eb4\u0e94-19 \u0ec0\u0e9e\u0eb2\u0eb0\u0ec0\u0eab\u0eb1\u0e99\u0ea7\u0ec8\u0eb2\u0e9b\u0eb1\u0e94\u0e88\u0eb8\u0e9a\u0eb1\u0e99 \u0e9b\u0eb0\u0ec0\u0e97\u0e94\u0ea5\u0eb2\u0ea7\u0e8d\u0eb1\u0e87\u0ea1\u0eb5\u0e84\u0ea7\u0eb2\u0ea1\u0eaa\u0ec8\u0ebd\u0e87 \u0ec1\u0ea5\u0eb0 \u0eaa\u0eb4\u0ec8\u0e87\u0e97\u0ec9\u0eb2\u0e97\u0eb2\u0e8d\u0eab\u0ebc\u0eb2\u0e8d\u0e97\u0eb5\u0ec8\u0e88\u0eb0\u0ec0\u0e81\u0eb5\u0e94\u0e81\u0eb2\u0e99\u0ec1\u0e9c\u0ec8\u0ea5\u0eb0\u0e9a\u0eb2\u0e94\u0e82\u0ead\u0e87\u0e9e\u0eb0\u0e8d\u0eb2\u0e94\u0e94\u0eb1\u0ec8\u0e87\u0e81\u0ec8\u0eb2\u0ea7\u0eae\u0ead\u0e9a\u0ec3\u0edd\u0ec8 \u0e8d\u0ec9\u0ead\u0e99\u0eaa\u0eb0\u0e9e\u0eb2\u0e9a\u0e81\u0eb2\u0e99\u0ea5\u0eb0\u0e9a\u0eb2\u0e94\u0e82\u0ead\u0e87\u0e9e\u0eb0\u0e8d\u0eb2\u0e94\u0e94\u0eb1\u0ec8\u0e87\u0e81\u0ec8\u0eb2\u0ea7\u0ea2\u0eb9\u0ec8\u0e9e\u0eb2\u0e81\u0e9e\u0eb7\u0ec9\u0e99 \u0ec1\u0ea5\u0eb0 \u0e97\u0ebb\u0ec8\u0ea7\u0ec2\u0ea5\u0e81\u0e8d\u0eb1\u0e87\u0eaa\u0eb7\u0e9a\u0e95\u0ecd\u0ec8\u0ec0\u0e9e\u0eb5\u0ec8\u0ea1\u0e82\u0eb6\u0ec9\u0e99. \u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0ec0\u0e99\u0eb7\u0ec9\u0ead\u0ec3\u0e99\u0eaa\u0eb3\u0e84\u0eb1\u0e99\u0ec3\u0e99\u0ec1\u0e88\u0ec9\u0e87\u0e81\u0eb2\u0e99\u0ea1\u0eb5\u0e84\u0eb7:<\/p>\n<p>\u0ea1\u0ead\u0e9a\u0ec3\u0eab\u0ec9\u0e81\u0eb0\u0e8a\u0ea7\u0e87\u0e9b\u0ec9\u0ead\u0e87\u0e81\u0eb1\u0e99\u0e84\u0ea7\u0eb2\u0ea1\u0eaa\u0eb0\u0eab\u0e87\u0ebb\u0e9a\u0eaa\u0ebb\u0ea1\u0e97\u0ebb\u0e9a\u0e81\u0eb1\u0e9a\u0e84\u0eb0\u0e99\u0eb0\u0eaa\u0eb0\u0ec0\u0e9e\u0eb2\u0eb0\u0e81\u0eb4\u0e94\u0e82\u0eb1\u0ec9\u0e99\u0e97\u0ec9\u0ead\u0e87\u0e96\u0eb4\u0ec8\u0e99\u0ec3\u0eab\u0ec9\u0ec0\u0e9e\u0eb5\u0ec8\u0ea1\u0e97\u0eb0\u0ea7\u0eb5\u0e81\u0ea7\u0e94\u0e81\u0eb2\u0e84\u0ebb\u0e99\u0ec0\u0e82\u0ebb\u0ec9\u0eb2-\u0ead\u0ead\u0e81\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0ea2\u0ec8\u0eb2\u0e87\u0ec0\u0e82\u0eb1\u0ec9\u0ea1\u0e87\u0ea7\u0e94\u0e81\u0ea7\u0ec8\u0eb2\u0ec0\u0e81\u0ebb\u0ec8\u0eb2, \u0e81\u0ecd\u0ea5\u0eb0\u0e99\u0eb5\u0e9e\u0ebb\u0e9a\u0ec0\u0eab\u0eb1\u0e99\u0e81\u0eb2\u0e99\u0ea5\u0eb1\u0e81\u0ea5\u0ead\u0e9a\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0ec1\u0e9a\u0e9a\u0e9a\u0ecd\u0ec8\u0e96\u0eb7\u0e81\u0e95\u0ec9\u0ead\u0e87\u0ec3\u0eab\u0ec9\u0e99\u0ecd\u0eb2\u0ec4\u0e9b\u0e81\u0ea7\u0e94\u0ec0\u0e8a\u0eb7\u0ec9\u0ead \u0ec1\u0ea5\u0eb0 \u0e81\u0eb1\u0e81\u0e9a\u0ecd\u0ea5\u0eb4\u0ec0\u0ea7\u0e99\u0ea2\u0eb9\u0ec8\u0eaa\u0eb9\u0e99\u0e97\u0eb5\u0ec8\u0ea5\u0eb1\u0e94\u0e81\u0ecd\u0eb2\u0e99\u0ebb\u0e94\u0ec4\u0ea7\u0ec9, \u0e9e\u0ec9\u0ead\u0ea1\u0ec3\u0eab\u0ec9\u0e94\u0ecd\u0eb2\u0ec0\u0e99\u0eb5\u0e99\u0ea1\u0eb2\u0e94\u0e95\u0eb0\u0e81\u0eb2\u0e99\u0e97\u0eb2\u0e87\u0e81\u0ebb\u0e94\u0edd\u0eb2\u0e8d \u0ec1\u0ea5\u0eb0 \u0ea5\u0eb0\u0e9a\u0ebd\u0e9a\u0e81\u0eb2\u0e99\u0e97\u0eb5\u0ec8\u0e81\u0ec8\u0ebd\u0ea7\u0e82\u0ec9\u0ead\u0e87 \u0ec1\u0ea5\u0eb0 \u0e9b\u0eb0\u0e81\u0eb2\u0e94\u0ead\u0ead\u0e81\u0ec3\u0eab\u0ec9\u0eaa\u0eb1\u0e87\u0e84\u0ebb\u0ea1\u0eae\u0eb1\u0e9a\u0eae\u0eb9\u0ec9\u0e81\u0ec8\u0ebd\u0ea7\u0e81\u0eb1\u0e9a\u0e9c\u0eb9\u0ec9\u0ea5\u0eb1\u0e81\u0ea5\u0ead\u0e9a\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0e99\u0eb1\u0ec9\u0e99.<\/p>\n<p>\u0ea1\u0ead\u0e9a\u0ec3\u0eab\u0ec9\u0e81\u0eb0\u0e8a\u0ea7\u0e87\u0e9b\u0ec9\u0ead\u0e87\u0e81\u0eb1\u0e99\u0e84\u0ea7\u0eb2\u0ea1\u0eaa\u0eb0\u0eab\u0e87\u0ebb\u0e9a\u0eaa\u0ebb\u0ea1\u0e97\u0ebb\u0e9a\u0e81\u0eb1\u0e9a\u0e99\u0eb0\u0e84\u0ead\u0e99\u0eab\u0ebc\u0ea7\u0e87, \u0e9a\u0eb1\u0e99\u0e94\u0eb2\u0ec1\u0e82\u0ea7\u0e87\u0e97\u0ebb\u0ec8\u0ea7\u0e9b\u0eb0\u0ec0\u0e97\u0e94 \u0ec1\u0ea5\u0eb0 \u0e9e\u0eb2\u0e81\u0eaa\u0ec8\u0ea7\u0e99\u0e97\u0eb5\u0ec8\u0e81\u0ec8\u0ebd\u0ea7\u0e82\u0ec9\u0ead\u0e87\u0e95\u0eb4\u0e94\u0e95\u0eb2\u0ea1 \u0ec1\u0ea5\u0eb0 \u0e81\u0ea7\u0e94\u0e81\u0eb2\u0eae\u0ec9\u0eb2\u0e99\u0e9a\u0eb1\u0e99\u0ec0\u0e97\u0eb4\u0e87, \u0eae\u0ec9\u0eb2\u0e99\u0e84\u0eb2\u0ea3\u0eb2\u0ec2\u0ead\u0ec0\u0e81\u0eb0 \u0ec1\u0ea5\u0eb0 \u0eae\u0ec9\u0eb2\u0e99\u0ec0\u0e81\u0ea1, \u0e81\u0ecd\u0ea5\u0eb0\u0e99\u0eb5\u0e81\u0ea7\u0e94\u0e9e\u0ebb\u0e9a\u0ec0\u0eab\u0eb1\u0e99\u0e9c\u0eb9\u0ec9\u0ea5\u0eb0\u0ec0\u0ea1\u0eb5\u0e94\u0e95\u0ecd\u0ec8\u0ec1\u0e88\u0ec9\u0e87\u0e81\u0eb2\u0e99\u0e84\u0eb1\u0ec9\u0e87\u0e97\u0ecd\u0eb2\u0ead\u0eb4\u0e94 \u0ec1\u0ea1\u0ec8\u0e99\u0ec3\u0eab\u0ec9\u0e81\u0ec8\u0eb2\u0ea7\u0ec0\u0e95\u0eb7\u0ead\u0e99\u0e9e\u0ec9\u0ead\u0ea1\u0e97\u0eb1\u0e87\u0ec0\u0eae\u0eb1\u0e94\u0e9a\u0ebb\u0e94\u0e9a\u0eb1\u0e99\u0e97\u0eb6\u0e81\u0ec4\u0ea7\u0ec9\u0ec0\u0e9b\u0eb1\u0e99\u0eab\u0ebc\u0eb1\u0e81\u0e96\u0eb2\u0e99, \u0eab\u0eb2\u0e81\u0e8d\u0eb1\u0e87\u0eaa\u0eb7\u0e9a\u0e95\u0ecd\u0ec8\u0ea5\u0eb0\u0ec0\u0ea1\u0eb5\u0e94\u0e95\u0eb7\u0ec8\u0ea1\u0ead\u0eb5\u0e81\u0ec1\u0ea1\u0ec8\u0e99\u0ec3\u0eab\u0ec9\u0ea2\u0eb6\u0e94\u0ec3\u0e9a\u0e97\u0eb0\u0e9a\u0ebd\u0e99, \u0ec3\u0eab\u0ec9\u0e9b\u0eb4\u0e94\u0e81\u0eb4\u0e94\u0e88\u0eb0\u0e81\u0eb2\u0e99\u0e9e\u0ec9\u0ead\u0ea1\u0e97\u0eb1\u0e87\u0e9b\u0eb1\u0e9a\u0ec3\u0edd\u0e95\u0eb2\u0ea1\u0ea5\u0eb0\u0e9a\u0ebd\u0e9a\u0e81\u0eb2\u0e99.<\/p>\n<p>\u0ec3\u0eab\u0ec9\u0e81\u0eb0\u0e8a\u0ea7\u0e87\u0e81\u0eb2\u0e99\u0e95\u0ec8\u0eb2\u0e87\u0e9b\u0eb0\u0ec0\u0e97\u0e94\u0eaa\u0ebb\u0ea1\u0e97\u0ebb\u0e9a\u0e81\u0eb1\u0e9a\u0e84\u0eb0\u0e99\u0eb0\u0eaa\u0eb0\u0ec0\u0e9e\u0eb2\u0eb0\u0e81\u0eb4\u0e94\u0ec2\u0e84\u0ea7\u0eb4\u0e94-19 \u0ec1\u0ea5\u0eb0 \u0e9e\u0eb2\u0e81\u0eaa\u0ec8\u0ea7\u0e99\u0e97\u0eb5\u0ec8\u0e81\u0ec8\u0ebd\u0ea7\u0e82\u0ec9\u0ead\u0e87\u0eaa\u0eb7\u0e9a\u0e95\u0ecd\u0ec8\u0e81\u0eb0\u0e81\u0ebd\u0ea1\u0e84\u0ea7\u0eb2\u0ea1\u0e9e\u0ec9\u0ead\u0ea1\u0ec3\u0e99\u0e81\u0eb2\u0e99\u0e9b\u0eb0\u0e95\u0eb4\u0e9a\u0eb1\u0e94\u0e8a\u0ec8\u0ead\u0e87\u0e97\u0eb2\u0e87\u0eaa\u0eb5\u0e82\u0ebd\u0ea7\u0e81\u0eb1\u0e9a \u0eaa\u0eaa \u0eab\u0ea7\u0ebd\u0e94\u0e99\u0eb2\u0ea1 \u0ec1\u0ea5\u0eb0 \u0eaa\u0e9b \u0e88\u0eb5\u0e99.<\/p>\n<p>\u0ec3\u0eab\u0ec9\u0e84\u0eb0\u0e99\u0eb0\u0eaa\u0eb0\u0ec0\u0e9e\u0eb2\u0eb0\u0e81\u0eb4\u0e94, \u0ead\u0ebb\u0e87\u0e81\u0eb2\u0e99\u0e9b\u0ebb\u0e81\u0e84\u0ead\u0e87\u0e97\u0ec9\u0ead\u0e87\u0e96\u0eb4\u0ec8\u0e99 \u0ec1\u0ea5\u0eb0 \u0e9e\u0eb2\u0e81\u0eaa\u0ec8\u0ea7\u0e99\u0e97\u0eb5\u0ec8\u0e81\u0ec8\u0ebd\u0ea7\u0e82\u0ec9\u0ead\u0e87\u0eaa\u0eb7\u0e9a\u0e95\u0ecd\u0ec8\u0e81\u0eb2\u0e99\u0ec0\u0e9e\u0eb5\u0ec8\u0ea1\u0e97\u0eb0\u0ea7\u0eb5\u0e81\u0eb2\u0e99\u0ec2\u0e84\u0eaa\u0eb0\u0e99\u0eb2, \u0e9b\u0eb0\u0e8a\u0eb2\u0eaa\u0ecd\u0eb2\u0e9e\u0eb1\u0e99 \u0ec1\u0ea5\u0eb0 \u0ec0\u0e9c\u0eb5\u0e8d\u0ec1\u0e9c\u0ec8\u0ec3\u0eab\u0ec9\u0e9b\u0eb0\u0e8a\u0eb2\u0e8a\u0ebb\u0e99\u0ec4\u0e94\u0ec9\u0eae\u0eb1\u0e9a\u0eae\u0eb9\u0ec9\u0e81\u0ec8\u0ebd\u0ea7\u0e81\u0eb1\u0e9a\u0e84\u0ea7\u0eb2\u0ea1\u0ead\u0eb1\u0e99\u0e95\u0eb0\u0ea5\u0eb2\u0e8d \u0ec1\u0ea5\u0eb0 \u0e84\u0ea7\u0eb2\u0ea1\u0eaa\u0ec8\u0ebd\u0e87\u0e97\u0eb5\u0ec8\u0e88\u0eb0\u0ec0\u0e81\u0eb5\u0e94\u0e81\u0eb2\u0e99\u0ea5\u0eb0\u0e9a\u0eb2\u0e94\u0eae\u0ead\u0e9a\u0ec3\u0edd\u0ec8\u0e82\u0ead\u0e87\u0e9e\u0eb0\u0e8d\u0eb2\u0e94\u0e94\u0eb1\u0ec8\u0e87\u0e81\u0ec8\u0eb2\u0ea7.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0eab\u0ec9\u0ead\u0e87\u0ea7\u0ec8\u0eb2\u0e81\u0eb2\u0e99\u0eaa\u0ecd\u0eb2\u0e99\u0eb1\u0e81\u0e87\u0eb2\u0e99\u0e99\u0eb2\u0e8d\u0ebb\u0e81\u0ea5\u0eb1\u0e94\u0e96\u0eb0\u0ea1\u0ebb\u0e99\u0e95\u0eb5 \u0ec4\u0e94\u0ec9\u0ead\u0ead\u0e81\u0ec1\u0e88\u0ec9\u0e87\u0e81\u0eb2\u0e99\u0e94\u0ec8\u0ea7\u0e99\u0ec3\u0e99\u0ea1\u0eb7\u0ec9\u0ea7\u0eb1\u0e99\u0e97\u0eb5 7 \u0eaa\u0eb4\u0e87\u0eab\u0eb2 \u0e97\u0eb5\u0ec8\u0e9c\u0ec8\u0eb2\u0e99\u0ea1\u0eb2 \u0ec0\u0e96\u0eb5\u0e87\u0e97\u0eb8\u0e81\u0e9e\u0eb2\u0e81\u0eaa\u0ec8\u0ea7\u0e99\u0ea5\u0ea7\u0ea1\u0e97\u0eb1\u0e87\u0e9e\u0ecd\u0ec8\u0ec1\u0ea1\u0ec8\u0e9b\u0eb0\u0e8a\u0eb2\u0e8a\u0ebb\u0e99\u0e9a\u0eb1\u0e99\u0e94\u0eb2\u0ec0\u0e9c\u0ebb\u0ec8\u0eb2\u0ec3\u0e99\u0e82\u0ead\u0e9a\u0ec0\u0e82\u0e94\u0e97\u0ebb\u0ec8\u0ea7\u0e9b\u0eb0\u0ec0\u0e97\u0e94\u0ec3\u0eab\u0ec9\u0ec0\u0e9e\u0eb5\u0ec8\u0ea1\u0e97\u0eb0\u0ea7\u0eb5\u0e82\u0eb6\u0ec9\u0e99\u0e81\u0ea7\u0ec8\u0eb2\u0ec0\u0e81\u0ebb\u0ec8\u0eb2\u0e81\u0ec8\u0ebd\u0ea7\u0e81\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0e9b\u0eb0\u0e95\u0eb4\u0e9a\u0eb1\u0e94\u0ea1\u0eb2\u0e94\u0e95\u0eb0\u0e81\u0eb2\u0e99\u0e9c\u0ec8\u0ead\u0e99\u0e9c\u0eb1\u0e99\u0e9b\u0ec9\u0ead\u0e87 \u0e81\u0eb1\u0e99, \u0e84\u0ea7\u0e9a\u0e84\u0eb8\u0ea1, \u0eaa\u0eb0\u0e81\u0eb1\u0e94\u0e81\u0eb1\u0ec9\u0e99 \u0ec1\u0ea5\u0eb0 \u0ec1\u0e81\u0ec9\u0ec4\u0e82\u0e81\u0eb2\u0e99\u0ec1\u0e9c\u0ec8\u0ea5\u0eb0\u0e9a\u0eb2\u0e94\u0e82\u0ead\u0e87\u0e9e\u0eb0\u0e8d\u0eb2\u0e94\u0ec2\u0e84\u0ea7\u0eb4\u0e94-19 \u0ec0\u0e9e\u0eb2\u0eb0\u0ec0\u0eab\u0eb1\u0e99\u0ea7\u0ec8\u0eb2\u0e9b\u0eb1\u0e94\u0e88\u0eb8\u0e9a\u0eb1\u0e99 \u0e9b\u0eb0\u0ec0\u0e97\u0e94\u0ea5\u0eb2\u0ea7\u0e8d\u0eb1\u0e87\u0ea1\u0eb5\u0e84\u0ea7\u0eb2\u0ea1\u0eaa\u0ec8\u0ebd\u0e87 \u0ec1\u0ea5\u0eb0 \u0eaa\u0eb4\u0ec8\u0e87\u0e97\u0ec9\u0eb2\u0e97\u0eb2\u0e8d\u0eab\u0ebc\u0eb2\u0e8d\u0e97\u0eb5\u0ec8\u0e88\u0eb0\u0ec0\u0e81\u0eb5\u0e94\u0e81\u0eb2\u0e99\u0ec1\u0e9c\u0ec8\u0ea5\u0eb0\u0e9a\u0eb2\u0e94\u0e82\u0ead\u0e87\u0e9e\u0eb0\u0e8d\u0eb2\u0e94\u0e94\u0eb1\u0ec8\u0e87\u0e81\u0ec8\u0eb2\u0ea7\u0eae\u0ead\u0e9a\u0ec3\u0edd\u0ec8&#8230;<\/p>\n","protected":false},"author":1,"featured_media":193,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,31],"tags":[],"class_list":["post-192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-18","category-31"],"featured_image_urls":{"full":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/123-696x364-1.jpg",696,364,false],"thumbnail":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/123-696x364-1-150x150.jpg",150,150,true],"medium":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/123-696x364-1-300x157.jpg",300,157,true],"medium_large":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/123-696x364-1.jpg",640,335,false],"large":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/123-696x364-1.jpg",640,335,false],"1536x1536":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/123-696x364-1.jpg",696,364,false],"2048x2048":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/123-696x364-1.jpg",696,364,false],"covernews-featured":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/123-696x364-1.jpg",696,364,false],"covernews-medium":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/123-696x364-1.jpg",540,282,false]},"author_info":{"display_name":"admin","author_link":"https:\/\/cdc.gov.la\/index.php\/author\/admin\/"},"category_info":"<a href=\"https:\/\/cdc.gov.la\/index.php\/category\/%e0%ba%82%e0%bb%88%e0%ba%b2%e0%ba%a7\/\" rel=\"category tag\">\u0e82\u0ec8\u0eb2\u0ea7<\/a> <a href=\"https:\/\/cdc.gov.la\/index.php\/category\/%e0%ba%82%e0%bb%88%e0%ba%b2%e0%ba%a7%e0%ba%94%e0%bb%88%e0%ba%a7%e0%ba%99\/\" rel=\"category tag\">\u0e82\u0ec8\u0eb2\u0ea7\u0e94\u0ec8\u0ea7\u0e99<\/a>","tag_info":"\u0e82\u0ec8\u0eb2\u0ea7\u0e94\u0ec8\u0ea7\u0e99","comment_count":"0","rttpg_featured_image_url":{"full":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/123-696x364-1.jpg",696,364,false],"landscape":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/123-696x364-1.jpg",696,364,false],"portraits":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/123-696x364-1.jpg",696,364,false],"thumbnail":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/123-696x364-1-150x150.jpg",150,150,true],"medium":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/123-696x364-1-300x157.jpg",300,157,true],"large":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/123-696x364-1.jpg",640,335,false],"1536x1536":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/123-696x364-1.jpg",696,364,false],"2048x2048":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/123-696x364-1.jpg",696,364,false],"covernews-featured":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/123-696x364-1.jpg",696,364,false],"covernews-medium":["https:\/\/cdc.gov.la\/wp-content\/uploads\/2020\/11\/123-696x364-1.jpg",540,282,false]},"rttpg_author":{"display_name":"admin","author_link":"https:\/\/cdc.gov.la\/index.php\/author\/admin\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/cdc.gov.la\/index.php\/category\/%e0%ba%82%e0%bb%88%e0%ba%b2%e0%ba%a7\/\" rel=\"category tag\">\u0e82\u0ec8\u0eb2\u0ea7<\/a> <a href=\"https:\/\/cdc.gov.la\/index.php\/category\/%e0%ba%82%e0%bb%88%e0%ba%b2%e0%ba%a7%e0%ba%94%e0%bb%88%e0%ba%a7%e0%ba%99\/\" rel=\"category tag\">\u0e82\u0ec8\u0eb2\u0ea7\u0e94\u0ec8\u0ea7\u0e99<\/a>","rttpg_excerpt":"\u0eab\u0ec9\u0ead\u0e87\u0ea7\u0ec8\u0eb2\u0e81\u0eb2\u0e99\u0eaa\u0ecd\u0eb2\u0e99\u0eb1\u0e81\u0e87\u0eb2\u0e99\u0e99\u0eb2\u0e8d\u0ebb\u0e81\u0ea5\u0eb1\u0e94\u0e96\u0eb0\u0ea1\u0ebb\u0e99\u0e95\u0eb5 \u0ec4\u0e94\u0ec9\u0ead\u0ead\u0e81\u0ec1\u0e88\u0ec9\u0e87\u0e81\u0eb2\u0e99\u0e94\u0ec8\u0ea7\u0e99\u0ec3\u0e99\u0ea1\u0eb7\u0ec9\u0ea7\u0eb1\u0e99\u0e97\u0eb5 7 \u0eaa\u0eb4\u0e87\u0eab\u0eb2 \u0e97\u0eb5\u0ec8\u0e9c\u0ec8\u0eb2\u0e99\u0ea1\u0eb2 \u0ec0\u0e96\u0eb5\u0e87\u0e97\u0eb8\u0e81\u0e9e\u0eb2\u0e81\u0eaa\u0ec8\u0ea7\u0e99\u0ea5\u0ea7\u0ea1\u0e97\u0eb1\u0e87\u0e9e\u0ecd\u0ec8\u0ec1\u0ea1\u0ec8\u0e9b\u0eb0\u0e8a\u0eb2\u0e8a\u0ebb\u0e99\u0e9a\u0eb1\u0e99\u0e94\u0eb2\u0ec0\u0e9c\u0ebb\u0ec8\u0eb2\u0ec3\u0e99\u0e82\u0ead\u0e9a\u0ec0\u0e82\u0e94\u0e97\u0ebb\u0ec8\u0ea7\u0e9b\u0eb0\u0ec0\u0e97\u0e94\u0ec3\u0eab\u0ec9\u0ec0\u0e9e\u0eb5\u0ec8\u0ea1\u0e97\u0eb0\u0ea7\u0eb5\u0e82\u0eb6\u0ec9\u0e99\u0e81\u0ea7\u0ec8\u0eb2\u0ec0\u0e81\u0ebb\u0ec8\u0eb2\u0e81\u0ec8\u0ebd\u0ea7\u0e81\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0e9b\u0eb0\u0e95\u0eb4\u0e9a\u0eb1\u0e94\u0ea1\u0eb2\u0e94\u0e95\u0eb0\u0e81\u0eb2\u0e99\u0e9c\u0ec8\u0ead\u0e99\u0e9c\u0eb1\u0e99\u0e9b\u0ec9\u0ead\u0e87 \u0e81\u0eb1\u0e99, \u0e84\u0ea7\u0e9a\u0e84\u0eb8\u0ea1, \u0eaa\u0eb0\u0e81\u0eb1\u0e94\u0e81\u0eb1\u0ec9\u0e99 \u0ec1\u0ea5\u0eb0 \u0ec1\u0e81\u0ec9\u0ec4\u0e82\u0e81\u0eb2\u0e99\u0ec1\u0e9c\u0ec8\u0ea5\u0eb0\u0e9a\u0eb2\u0e94\u0e82\u0ead\u0e87\u0e9e\u0eb0\u0e8d\u0eb2\u0e94\u0ec2\u0e84\u0ea7\u0eb4\u0e94-19 \u0ec0\u0e9e\u0eb2\u0eb0\u0ec0\u0eab\u0eb1\u0e99\u0ea7\u0ec8\u0eb2\u0e9b\u0eb1\u0e94\u0e88\u0eb8\u0e9a\u0eb1\u0e99 \u0e9b\u0eb0\u0ec0\u0e97\u0e94\u0ea5\u0eb2\u0ea7\u0e8d\u0eb1\u0e87\u0ea1\u0eb5\u0e84\u0ea7\u0eb2\u0ea1\u0eaa\u0ec8\u0ebd\u0e87 \u0ec1\u0ea5\u0eb0 \u0eaa\u0eb4\u0ec8\u0e87\u0e97\u0ec9\u0eb2\u0e97\u0eb2\u0e8d\u0eab\u0ebc\u0eb2\u0e8d\u0e97\u0eb5\u0ec8\u0e88\u0eb0\u0ec0\u0e81\u0eb5\u0e94\u0e81\u0eb2\u0e99\u0ec1\u0e9c\u0ec8\u0ea5\u0eb0\u0e9a\u0eb2\u0e94\u0e82\u0ead\u0e87\u0e9e\u0eb0\u0e8d\u0eb2\u0e94\u0e94\u0eb1\u0ec8\u0e87\u0e81\u0ec8\u0eb2\u0ea7\u0eae\u0ead\u0e9a\u0ec3\u0edd\u0ec8...","_links":{"self":[{"href":"https:\/\/cdc.gov.la\/index.php\/wp-json\/wp\/v2\/posts\/192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdc.gov.la\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cdc.gov.la\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cdc.gov.la\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cdc.gov.la\/index.php\/wp-json\/wp\/v2\/comments?post=192"}],"version-history":[{"count":1,"href":"https:\/\/cdc.gov.la\/index.php\/wp-json\/wp\/v2\/posts\/192\/revisions"}],"predecessor-version":[{"id":194,"href":"https:\/\/cdc.gov.la\/index.php\/wp-json\/wp\/v2\/posts\/192\/revisions\/194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdc.gov.la\/index.php\/wp-json\/wp\/v2\/media\/193"}],"wp:attachment":[{"href":"https:\/\/cdc.gov.la\/index.php\/wp-json\/wp\/v2\/media?parent=192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cdc.gov.la\/index.php\/wp-json\/wp\/v2\/categories?post=192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cdc.gov.la\/index.php\/wp-json\/wp\/v2\/tags?post=192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}